{"id":201,"date":"2023-09-21T14:33:18","date_gmt":"2023-09-21T06:33:18","guid":{"rendered":"https:\/\/www.sinch.top\/?page_id=201"},"modified":"2023-11-25T22:16:57","modified_gmt":"2023-11-25T14:16:57","slug":"faq","status":"publish","type":"page","link":"https:\/\/www.sinch.top\/el\/faq\/","title":{"rendered":"\u03a3\u03a5\u03a7\u039d\u0388\u03a3 \u0395\u03a1\u03a9\u03a4\u0389\u03a3\u0395\u0399\u03a3"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"201\" class=\"elementor elementor-201\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8af958d elementor-section-boxed elementor-section-height-default elementor-section-height-default tf-sticky-section tf-sticky-no\" data-id=\"8af958d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;tf_sticky&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a87de4c\" data-id=\"a87de4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e6ef75 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8e6ef75\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u03a3\u03a5\u03a7\u039d\u0388\u03a3 \u0395\u03a1\u03a9\u03a4\u0389\u03a3\u0395\u0399\u03a3<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c63e51c elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"c63e51c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0391\u03c1\u03c7\u03b9\u03ba\u03ae \u03c3\u03b5\u03bb\u03af\u03b4\u03b1<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Faq<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c3bc59 elementor-section-boxed elementor-section-height-default elementor-section-height-default tf-sticky-section tf-sticky-no\" data-id=\"0c3bc59\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;tf_sticky&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0ce507\" data-id=\"d0ce507\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5816af0 elementor-section-boxed elementor-section-height-default elementor-section-height-default tf-sticky-section tf-sticky-no\" data-id=\"5816af0\" data-element_type=\"section\" data-settings=\"{&quot;tf_sticky&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-57917bb\" data-id=\"57917bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22c7b32 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"22c7b32\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a04cb70b0d22\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-22c7b32\">\n                        <a href=\"#collapse-e66b6426a04cb70b0d22\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-e66b6426a04cb70b0d22\" aria-expanded=\"false\" aria-controls=\"Collapse-e66b6426a04cb70b0d22\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-plus-circle\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-circle-minus\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Where is your company?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-e66b6426a04cb70b0d22\" class=\"collapse\" aria-labelledby=\"primaryHeading-0-22c7b32\" data-parent=\"#accordion-6a04cb70b0d22\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Our head office is located in Guangzhou City, Guangdong Province, China (Mainland).                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-22c7b32\">\n                        <a href=\"#collapse-4d37df36a04cb70b0d22\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4d37df36a04cb70b0d22\" aria-expanded=\"true\" aria-controls=\"Collapse-4d37df36a04cb70b0d22\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-plus-circle\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-circle-minus\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">What is your terms of payment?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4d37df36a04cb70b0d22\" class=\"show collapse\" aria-labelledby=\"primaryHeading-1-22c7b32\" data-parent=\"#accordion-6a04cb70b0d22\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>\u00a0T\/T 30% as deposit, and 70% before delivery. We\u2019ll show you the photos of the products and packages before you pay the balance.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-22c7b32\">\n                        <a href=\"#collapse-4dee3a66a04cb70b0d22\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4dee3a66a04cb70b0d22\" aria-expanded=\"false\" aria-controls=\"Collapse-4dee3a66a04cb70b0d22\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-plus-circle\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-circle-minus\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">What is your terms of delivery?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4dee3a66a04cb70b0d22\" class=\"collapse\" aria-labelledby=\"primaryHeading-2-22c7b32\" data-parent=\"#accordion-6a04cb70b0d22\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>EXW\u00a0and\u00a0FOB<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-22c7b32\">\n                        <a href=\"#collapse-772746e6a04cb70b0d22\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-772746e6a04cb70b0d22\" aria-expanded=\"false\" aria-controls=\"Collapse-772746e6a04cb70b0d22\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-plus-circle\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-circle-minus\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">How about your delivery time?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-772746e6a04cb70b0d22\" class=\"collapse\" aria-labelledby=\"primaryHeading-3-22c7b32\" data-parent=\"#accordion-6a04cb70b0d22\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>It will take approximately 20 days after receiving your deposit. The specific delivery time will depend on the items and the quantity of your order<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-22c7b32\">\n                        <a href=\"#collapse-2cec2026a04cb70b0d22\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-2cec2026a04cb70b0d22\" aria-expanded=\"false\" aria-controls=\"Collapse-2cec2026a04cb70b0d22\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-plus-circle\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-circle-minus\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Do you test all your goods before delivery?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-2cec2026a04cb70b0d22\" class=\"collapse\" aria-labelledby=\"primaryHeading-4-22c7b32\" data-parent=\"#accordion-6a04cb70b0d22\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Yes, we have 100% test before delivery<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-22c7b32\">\n                        <a href=\"#collapse-678e6676a04cb70b0d22\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-678e6676a04cb70b0d22\" aria-expanded=\"false\" aria-controls=\"Collapse-678e6676a04cb70b0d22\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-plus-circle\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-circle-minus\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Can you provide samples\uff1f<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-678e6676a04cb70b0d22\" class=\"collapse\" aria-labelledby=\"primaryHeading-5-22c7b32\" data-parent=\"#accordion-6a04cb70b0d22\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Yes, we can supply the sample , but the customers have to pay the sample cost and the courier costs.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-22c7b32\">\n                        <a href=\"#collapse-1657bcb6a04cb70b0d22\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-1657bcb6a04cb70b0d22\" aria-expanded=\"false\" aria-controls=\"Collapse-1657bcb6a04cb70b0d22\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-plus-circle\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-circle-minus\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">What is your terms of packing?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-1657bcb6a04cb70b0d22\" class=\"collapse\" aria-labelledby=\"primaryHeading-6-22c7b32\" data-parent=\"#accordion-6a04cb70b0d22\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>\u00a0Generally, we pack our goods in\u00a0 boxes .<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-7-22c7b32\">\n                        <a href=\"#collapse-aca6d8e6a04cb70b0d22\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-aca6d8e6a04cb70b0d22\" aria-expanded=\"false\" aria-controls=\"Collapse-aca6d8e6a04cb70b0d22\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-plus-circle\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-circle-minus\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Are your products used worldwide?<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-aca6d8e6a04cb70b0d22\" class=\"collapse\" aria-labelledby=\"primaryHeading-7-22c7b32\" data-parent=\"#accordion-6a04cb70b0d22\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Yes,we supply Europe, America, Southeast Asia, the Middle East, and other regions,, Most auto parts are used universally in application<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2487b05 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2487b05\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Need any support ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db1cbd5 elementor-widget elementor-widget-text-editor\" data-id=\"db1cbd5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>If you have any questions, please feel free to contact us at any time. We will wholeheartedly serve you.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ffadb60 elementor-section-boxed elementor-section-height-default elementor-section-height-default tf-sticky-section tf-sticky-no elementor-invisible\" data-id=\"ffadb60\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;tf_sticky&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-df08e9f\" data-id=\"df08e9f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2729820 elementor-widget elementor-widget-metform\" data-id=\"2729820\" data-element_type=\"widget\" data-widget_type=\"metform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"mf-response-props-id-1685\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"1685\" >\n\t\t\t\t\n\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-2729820-1685\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"1685\"\r\n\t\t\tdata-action=\"https:\/\/www.sinch.top\/el\/wp-json\/metform\/v1\/entries\/insert\/1685\"\r\n\t\t\tdata-wp-nonce=\"98f7e463aa\"\r\n\t\t\tdata-form-nonce=\"b4487daa85\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"contact_form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-1685\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c4d5e30 elementor-section-boxed elementor-section-height-default elementor-section-height-default tf-sticky-section tf-sticky-no\" data-id=\"6c4d5e30\" data-element_type=\"section\" data-settings=\"{&quot;tf_sticky&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1594c930\" data-id=\"1594c930\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f09f935 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3f09f935\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u039a\u03b1\u03c1\u03bf\u03c5\u03b6\u03ad\u03bb \u0395\u03b9\u03ba\u03cc\u03bd\u03b1\u03c2\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.sinch.top\/wp-content\/uploads\/2023\/10\/c7f064a78eb63eff7088fef0d5fb9e6-300x225.jpg\" alt=\"c7f064a78eb63eff7088fef0d5fb9e6\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.sinch.top\/wp-content\/uploads\/2023\/10\/248dffee3520f1a6d15b58712dc418f-300x225.jpg\" alt=\"248dffee3520f1a6d15b58712dc418f\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.sinch.top\/wp-content\/uploads\/2023\/10\/4b8e34dfc5cfc981ec2835a1db4d00b-300x225.jpg\" alt=\"4b8e34dfc5cfc981ec2835a1db4d00b\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.sinch.top\/wp-content\/uploads\/2023\/10\/a47eeeedca72feda4ca68ad058eff84-300x225.jpg\" alt=\"a47eeeedca72feda4ca68ad058eff84\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.sinch.top\/wp-content\/uploads\/2023\/10\/9714ff3fa4fc45ba44e7b3d4bafb650-300x225.jpg\" alt=\"9714ff3fa4fc45ba44e7b3d4bafb650\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.sinch.top\/wp-content\/uploads\/2023\/10\/6d7f3305d012d31c7da08e9614f041a-300x225.jpg\" alt=\"6d7f3305d012d31c7da08e9614f041a\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.sinch.top\/wp-content\/uploads\/2023\/10\/1914d72f11f0f18272883ed9a02f380-300x225.jpg\" alt=\"1914d72f11f0f18272883ed9a02f380\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.sinch.top\/wp-content\/uploads\/2023\/10\/1409db1b67e6f5d1bc2d4acd890b7c7-300x225.jpg\" alt=\"1409db1b67e6f5d1bc2d4acd890b7c7\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>FAQ Home Faq Where is your company? Our head office is located in Guangzhou City, Guangdong Province, China (Mainland). What is your terms of payment? T\/T 30% as deposit, and 70% before delivery. We\u2019ll show you the photos of the products and packages before you pay the balance. What is your terms of delivery? EXW\u00a0and\u00a0FOB [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-201","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.sinch.top\/el\/wp-json\/wp\/v2\/pages\/201"}],"collection":[{"href":"https:\/\/www.sinch.top\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sinch.top\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sinch.top\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sinch.top\/el\/wp-json\/wp\/v2\/comments?post=201"}],"version-history":[{"count":0,"href":"https:\/\/www.sinch.top\/el\/wp-json\/wp\/v2\/pages\/201\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sinch.top\/el\/wp-json\/wp\/v2\/media?parent=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}